{"id":1075,"date":"2003-11-16T01:00:00","date_gmt":"2003-11-16T00:00:00","guid":{"rendered":"http:\/\/www.musicadeon.com\/index.php\/2003\/11\/16\/a-vos-agendas-21-12-2003-6\/"},"modified":"2003-11-16T01:00:00","modified_gmt":"2003-11-16T00:00:00","slug":"a-vos-agendas-21-12-2003-6","status":"publish","type":"post","link":"http:\/\/www.musicadeon.com\/index.php\/2003\/11\/16\/a-vos-agendas-21-12-2003-6\/","title":{"rendered":"\u00c0 vos agendas (21-12-2003)"},"content":{"rendered":"<p>Le Dimanche 21 D\u00e9cembre 2003 \u00e0 15h30 \u00ab\u00a0Les Senteurs de Lys\u00a0\u00bb vous invite \u00e0 danser avec DIDIER ET MAGALI \u00e0 la roche (Belgique)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Dimanche 21 D\u00e9cembre 2003 \u00e0 15h30 \u00ab\u00a0Les Senteurs de Lys\u00a0\u00bb vous invite \u00e0 danser avec DIDIER ET MAGALI \u00e0 la roche (Belgique)<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/www.musicadeon.com\/index.php\/wp-json\/wp\/v2\/posts\/1075"}],"collection":[{"href":"http:\/\/www.musicadeon.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.musicadeon.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.musicadeon.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.musicadeon.com\/index.php\/wp-json\/wp\/v2\/comments?post=1075"}],"version-history":[{"count":0,"href":"http:\/\/www.musicadeon.com\/index.php\/wp-json\/wp\/v2\/posts\/1075\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.musicadeon.com\/index.php\/wp-json\/wp\/v2\/media?parent=1075"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.musicadeon.com\/index.php\/wp-json\/wp\/v2\/categories?post=1075"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.musicadeon.com\/index.php\/wp-json\/wp\/v2\/tags?post=1075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}